{"id":355,"date":"2025-08-26T17:16:25","date_gmt":"2025-08-26T17:16:25","guid":{"rendered":"https:\/\/ecooltours.com.mx\/index.php\/events-list-style\/"},"modified":"2025-08-26T17:16:25","modified_gmt":"2025-08-26T17:16:25","slug":"events-list-style","status":"publish","type":"page","link":"https:\/\/ecooltours.com.mx\/index.php\/events-list-style\/","title":{"rendered":"Events \u2013 List Style"},"content":{"rendered":"        <div class='list_with_filter_section mep_event_list'>\n\t\t\t            <div class=\"all_filter_item mep_event_list_sec\" id='mep_event_list_abr6a581b77650b2'>\n\t\t\t\t<div class=\"mage_grid_box\">            <\/div>\n        <\/div>\n\t\t            <input type=\"hidden\" name=\"pagination_per_page\" value=\"10\"\/>\r\n            <input type=\"hidden\" name=\"pagination_style\" value=\"load_more\"\/>\r\n                    <\/div>\n        <script>\n            jQuery(document).ready(function () {\n                var containerEl = document.querySelector('#mep_event_list_abr6a581b77650b2');\n                var mixer = mixitup(containerEl, {\n                    selectors: {\n                        target: '.mep-event-list-loop',\n                        control: '[data-mixitup-control]'\n                    }\n                });\n                \/\/ Handle title filter input\n                jQuery('input[name=\"filter_with_title\"]').on('keyup', function () {\n                    var searchText = jQuery(this).val().toLowerCase();\n                    var items = jQuery('.mep-event-list-loop');\n                    items.each(function () {\n                        var itemTitle = jQuery(this).data('title').toLowerCase();\n                        if (itemTitle.indexOf(searchText) > -1) {\n                            jQuery(this).show();\n                        } else {\n                            jQuery(this).hide();\n                        }\n                    });\n                });\n                \/\/ Handle date filter change\n                jQuery('input[name=\"filter_with_date\"]').on('change', function () {\n                    var selectedDate = jQuery(this).val();\n                    var items = jQuery('.mep-event-list-loop');\n                    if (!selectedDate) {\n                        items.show();\n                    } else {\n                        var filterDate = new Date(selectedDate);\n                        filterDate.setHours(0, 0, 0, 0); \/\/ Reset time part for date comparison\n                        items.each(function () {\n                            var itemDate = new Date(jQuery(this).data('date'));\n                            itemDate.setHours(0, 0, 0, 0); \/\/ Reset time part for date comparison\n                            if (itemDate.getTime() === filterDate.getTime()) {\n                                jQuery(this).show();\n                            } else {\n                                jQuery(this).hide();\n                            }\n                        });\n                    }\n                });\n                \/\/ Handle state filter change\n                jQuery('select[name=\"filter_with_state\"]').on('change', function () {\n                    var state = jQuery(this).val();\n                    var items = jQuery('.mep-event-list-loop');\n                    if (state === '') {\n                        items.show();\n                    } else {\n                        items.each(function () {\n                            var itemState = jQuery(this).data('state');\n                            if (itemState === state) {\n                                jQuery(this).show();\n                            } else {\n                                jQuery(this).hide();\n                            }\n                        });\n                    }\n                });\n                \/\/ Handle city filter change\n                jQuery('select[name=\"filter_with_city\"]').on('change', function () {\n                    var city = jQuery(this).val();\n                    var items = jQuery('.mep-event-list-loop');\n                    if (city === '') {\n                        items.show();\n                    } else {\n                        items.each(function () {\n                            var itemCity = jQuery(this).data('city-name');\n                            if (itemCity === city) {\n                                jQuery(this).show();\n                            } else {\n                                jQuery(this).hide();\n                            }\n                        });\n                    }\n                });\n\t\t\t\t\t\t\t\t            });\n        <\/script>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"class_list":["post-355","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ecooltours.com.mx\/index.php\/wp-json\/wp\/v2\/pages\/355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecooltours.com.mx\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ecooltours.com.mx\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ecooltours.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ecooltours.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=355"}],"version-history":[{"count":0,"href":"https:\/\/ecooltours.com.mx\/index.php\/wp-json\/wp\/v2\/pages\/355\/revisions"}],"wp:attachment":[{"href":"https:\/\/ecooltours.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}